{"id":302841,"date":"2025-07-26T17:15:13","date_gmt":"2025-07-26T16:15:13","guid":{"rendered":"https:\/\/ecosupplements.be\/product\/panaseus-for-allergies-50-caps\/"},"modified":"2025-08-28T03:45:23","modified_gmt":"2025-08-28T02:45:23","slug":"panaseus-for-allergies-50-caps","status":"publish","type":"product","link":"https:\/\/ecosupplements.be\/fr\/produit\/panaseus-for-allergies-50-caps\/","title":{"rendered":"PANASEUS Pour les allergies (50 g\u00e9lules)"},"content":{"rendered":"<h2>PANASEUS For allergies (50 caps)<\/h2>\n<p>D\u00e9couvrez PANASEUS For allergies, un produit con\u00e7u avec des ingr\u00e9dients d&#8217;origine naturelle, s\u00e9lectionn\u00e9s pour leur grande puret\u00e9 et qualit\u00e9.Chaque capsule est formul\u00e9e \u00e0 partir d&#8217;extraits de plantes comme le Sophora japonica,la Scutellaria baicalensis,et bien d&#8217;autres encore.<\/p>\n<h3>Ingr\u00e9dients principaux<\/h3>\n<ul>\n<li>Extrait de Sophora japonica : contient 98% de querc\u00e9tine.<\/li>\n<li>Extrait de Scutellaria baicalensis : riche en bajkaline \u00e0 hauteur de 85%.<\/li>\n<li>extraits concentr\u00e9s de Solidago virgaurea, Cistus creticus et Perilla frutescens.<\/li>\n<li>Inuline issue du chicor\u00e9e &#8211; une source naturelle de fibres.<\/li>\n<\/ul>\n<h3>Contenu et emballage<\/h3>\n<p>Ce produit se pr\u00e9sente sous forme d&#8217;un flacon contenant 50 capsules v\u00e9g\u00e9tales faciles \u00e0 consommer. Les capsules sont fabriqu\u00e9es \u00e0 partir de cellulose v\u00e9g\u00e9tale, adapt\u00e9es pour une alimentation v\u00e9g\u00e9tarienne.<\/p>\n<h3>Utilisation<\/h3>\n<p>Pour un usage quotidien simple, il est recommand\u00e9 de prendre une capsule par jour avec beaucoup d&#8217;eau apr\u00e8s le premier repas. Ce format pratique vous permettra d&#8217;int\u00e9grer facilement ce produit dans votre routine quotidienne sans perturber vos activit\u00e9s habituelles.<\/p>\n<h4>Note:<\/h4>\n<p>Ce produit ne doit pas d\u00e9passer la dose journali\u00e8re indiqu\u00e9e. Il n&#8217;est pas destin\u00e9 \u00e0 remplacer une alimentation vari\u00e9e. Avant utilisation, les personnes sous m\u00e9dication devraient consulter un professionnel sant\u00e9. Non recommand\u00e9 pour les enfants ni les femmes enceintes ou allaitantes.<\/p>\n<h3>Conservation<\/h3>\n<p>Gardez le flacon dans un endroit sec et frais, hors de port\u00e9e des enfants. Ce produit est exempt de m\u00e9taux lourds tels que l&#8217;arsenic,le cadmium ou le mercure garantissant ainsi sa puret\u00e9 et s\u00e9curit\u00e9.<\/p>\n<p>Avec PANASEUS For allergies (50 caps), optez pour un choix naturel qui s&#8217;int\u00e8gre harmonieusement dans votre vie active au quotidien!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PANASEUS For allergies (50 caps) D\u00e9couvrez PANASEUS For allergies, un produit con\u00e7u avec des ingr\u00e9dients d&#8217;origine naturelle, s\u00e9lectionn\u00e9s pour leur grande puret\u00e9 et qualit\u00e9.Chaque capsule est formul\u00e9e \u00e0 partir d&#8217;extraits de plantes comme le Sophora japonica,la Scutellaria baicalensis,et bien d&#8217;autres encore. Ingr\u00e9dients principaux Extrait de Sophora japonica : contient 98% de querc\u00e9tine. Extrait de Scutellaria [&#8230;]\n","protected":false},"featured_media":276981,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_brand":[5379],"product_cat":[5052,5094,5053],"product_tag":[],"class_list":["post-302841","product","type-product","status-publish","has-post-thumbnail","product_brand-panaseus-2","product_cat-sante-et-bien-etre","product_cat-supplements-a-base-de-plantes","product_cat-vitamines-et-mineraux","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>PANASEUS Pour les allergies (50 g\u00e9lules) - ECO Supplements<\/title>\n<meta name=\"description\" content=\"Wij hebben een ruime keuze aan producten van PANASEUS Pour les allergies (50 g\u00e9lules) . Winkel bij Eco Supplements altijd gratis verzending boven 100\u20ac\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecosupplements.be\/fr\/produit\/panaseus-for-allergies-50-caps\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PANASEUS Pour les allergies (50 g\u00e9lules)\" \/>\n<meta property=\"og:description\" content=\"Wij hebben een ruime keuze aan producten van PANASEUS Pour les allergies (50 g\u00e9lules) . Winkel bij Eco Supplements altijd gratis verzending boven 100\u20ac\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecosupplements.be\/fr\/produit\/panaseus-for-allergies-50-caps\/\" \/>\n<meta property=\"og:site_name\" content=\"ECO Supplements\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-28T02:45:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecosupplements.be\/wp-content\/uploads\/2025\/08\/Panaseus-PANASEUS-For-allergies-50-caps.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"12.14&nbsp;&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/ecosupplements.be\\\/fr\\\/produit\\\/panaseus-for-allergies-50-caps\\\/\",\"url\":\"https:\\\/\\\/ecosupplements.be\\\/fr\\\/produit\\\/panaseus-for-allergies-50-caps\\\/\",\"name\":\"PANASEUS Pour les allergies (50 g\u00e9lules) - ECO Supplements\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecosupplements.be\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ecosupplements.be\\\/fr\\\/produit\\\/panaseus-for-allergies-50-caps\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ecosupplements.be\\\/fr\\\/produit\\\/panaseus-for-allergies-50-caps\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ecosupplements.be\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/PANASEUS-For-allergies-50-caps.jpg\",\"datePublished\":\"2025-07-26T16:15:13+00:00\",\"dateModified\":\"2025-08-28T02:45:23+00:00\",\"description\":\"Wij hebben een ruime keuze aan producten van PANASEUS Pour les allergies (50 g\u00e9lules) . Winkel bij Eco Supplements altijd gratis verzending boven 100\u20ac\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecosupplements.be\\\/fr\\\/produit\\\/panaseus-for-allergies-50-caps\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ecosupplements.be\\\/fr\\\/produit\\\/panaseus-for-allergies-50-caps\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ecosupplements.be\\\/fr\\\/produit\\\/panaseus-for-allergies-50-caps\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ecosupplements.be\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/PANASEUS-For-allergies-50-caps.jpg\",\"contentUrl\":\"https:\\\/\\\/ecosupplements.be\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/PANASEUS-For-allergies-50-caps.jpg\",\"width\":460,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecosupplements.be\\\/fr\\\/produit\\\/panaseus-for-allergies-50-caps\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ecosupplements.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/ecosupplements.be\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PANASEUS Pour les allergies (50 g\u00e9lules)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecosupplements.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ecosupplements.be\\\/fr\\\/\",\"name\":\"ECO Supplements\",\"description\":\"Eco Supplements - Gezonde supplementen\",\"publisher\":{\"@id\":\"https:\\\/\\\/ecosupplements.be\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ecosupplements.be\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ecosupplements.be\\\/fr\\\/#organization\",\"name\":\"Eco Supplements\",\"url\":\"https:\\\/\\\/ecosupplements.be\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ecosupplements.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ecosupplements.be\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/ecosupplement-family.png\",\"contentUrl\":\"https:\\\/\\\/ecosupplements.be\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/ecosupplement-family.png\",\"width\":593,\"height\":374,\"caption\":\"Eco Supplements\"},\"image\":{\"@id\":\"https:\\\/\\\/ecosupplements.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<meta property=\"product:brand\" content=\"Panaseus\" \/>\n<meta property=\"product:price:amount\" content=\"12.14\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"5904194061647\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"PANASEUS Pour les allergies (50 g\u00e9lules) - ECO Supplements","description":"Wij hebben een ruime keuze aan producten van PANASEUS Pour les allergies (50 g\u00e9lules) . Winkel bij Eco Supplements altijd gratis verzending boven 100\u20ac","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecosupplements.be\/fr\/produit\/panaseus-for-allergies-50-caps\/","og_locale":"fr_FR","og_type":"article","og_title":"PANASEUS Pour les allergies (50 g\u00e9lules)","og_description":"Wij hebben een ruime keuze aan producten van PANASEUS Pour les allergies (50 g\u00e9lules) . Winkel bij Eco Supplements altijd gratis verzending boven 100\u20ac","og_url":"https:\/\/ecosupplements.be\/fr\/produit\/panaseus-for-allergies-50-caps\/","og_site_name":"ECO Supplements","article_modified_time":"2025-08-28T02:45:23+00:00","og_image":[{"width":460,"height":460,"url":"https:\/\/ecosupplements.be\/wp-content\/uploads\/2025\/08\/Panaseus-PANASEUS-For-allergies-50-caps.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"12.14&nbsp;&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/ecosupplements.be\/fr\/produit\/panaseus-for-allergies-50-caps\/","url":"https:\/\/ecosupplements.be\/fr\/produit\/panaseus-for-allergies-50-caps\/","name":"PANASEUS Pour les allergies (50 g\u00e9lules) - ECO Supplements","isPartOf":{"@id":"https:\/\/ecosupplements.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ecosupplements.be\/fr\/produit\/panaseus-for-allergies-50-caps\/#primaryimage"},"image":{"@id":"https:\/\/ecosupplements.be\/fr\/produit\/panaseus-for-allergies-50-caps\/#primaryimage"},"thumbnailUrl":"https:\/\/ecosupplements.be\/wp-content\/uploads\/2025\/08\/PANASEUS-For-allergies-50-caps.jpg","datePublished":"2025-07-26T16:15:13+00:00","dateModified":"2025-08-28T02:45:23+00:00","description":"Wij hebben een ruime keuze aan producten van PANASEUS Pour les allergies (50 g\u00e9lules) . Winkel bij Eco Supplements altijd gratis verzending boven 100\u20ac","breadcrumb":{"@id":"https:\/\/ecosupplements.be\/fr\/produit\/panaseus-for-allergies-50-caps\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecosupplements.be\/fr\/produit\/panaseus-for-allergies-50-caps\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ecosupplements.be\/fr\/produit\/panaseus-for-allergies-50-caps\/#primaryimage","url":"https:\/\/ecosupplements.be\/wp-content\/uploads\/2025\/08\/PANASEUS-For-allergies-50-caps.jpg","contentUrl":"https:\/\/ecosupplements.be\/wp-content\/uploads\/2025\/08\/PANASEUS-For-allergies-50-caps.jpg","width":460,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/ecosupplements.be\/fr\/produit\/panaseus-for-allergies-50-caps\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ecosupplements.be\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/ecosupplements.be\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"PANASEUS Pour les allergies (50 g\u00e9lules)"}]},{"@type":"WebSite","@id":"https:\/\/ecosupplements.be\/fr\/#website","url":"https:\/\/ecosupplements.be\/fr\/","name":"ECO Supplements","description":"Eco Supplements - Gezonde supplementen","publisher":{"@id":"https:\/\/ecosupplements.be\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecosupplements.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ecosupplements.be\/fr\/#organization","name":"Eco Supplements","url":"https:\/\/ecosupplements.be\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ecosupplements.be\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/ecosupplements.be\/wp-content\/uploads\/2022\/06\/ecosupplement-family.png","contentUrl":"https:\/\/ecosupplements.be\/wp-content\/uploads\/2022\/06\/ecosupplement-family.png","width":593,"height":374,"caption":"Eco Supplements"},"image":{"@id":"https:\/\/ecosupplements.be\/fr\/#\/schema\/logo\/image\/"}}]},"product_brand":"Panaseus","product_price_amount":"12.14","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"5904194061647","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/ecosupplements.be\/fr\/wp-json\/wp\/v2\/product\/302841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecosupplements.be\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ecosupplements.be\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ecosupplements.be\/fr\/wp-json\/wp\/v2\/comments?post=302841"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecosupplements.be\/fr\/wp-json\/wp\/v2\/media\/276981"}],"wp:attachment":[{"href":"https:\/\/ecosupplements.be\/fr\/wp-json\/wp\/v2\/media?parent=302841"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ecosupplements.be\/fr\/wp-json\/wp\/v2\/product_brand?post=302841"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ecosupplements.be\/fr\/wp-json\/wp\/v2\/product_cat?post=302841"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ecosupplements.be\/fr\/wp-json\/wp\/v2\/product_tag?post=302841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}